{"id":1027,"date":"2017-12-08T07:00:09","date_gmt":"2017-12-08T07:00:09","guid":{"rendered":"http:\/\/urbanvolcano.net\/es\/?p=1027"},"modified":"2025-03-30T21:02:09","modified_gmt":"2025-03-30T21:02:09","slug":"el-hombre-que-susurraba-a-los-perros","status":"publish","type":"post","link":"https:\/\/urbanvolcano.net\/es\/el-hombre-que-susurraba-a-los-perros\/","title":{"rendered":"El hombre que susurraba a los perros"},"content":{"rendered":"\n<aside class=\"other-formats\">Otros formatos: <a title=\"El hombre que susurraba a los perros (PDF)\" href=\"https:\/\/urbanvolcano.net\/ebooks\/es\/pdf\/el-hombre-que-susurraba-a-los-perros.pdf\">PDF<\/a> | <a title=\"The dog whisperer (english)\" href=\"https:\/\/urbanvolcano.net\/en\/the-dog-whisperer\/\">english<\/a> | <a title=\"Hundahv\u00edslarinn (\u00edslenska)\" href=\"https:\/\/urbanvolcano.net\/is\/hundahvislarinn\/\">\u00edslenska<\/a><\/aside>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49.png\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49-300x300.png\" alt=\"El hombre que susurraba a los perros \u2014 Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson\" class=\"wp-image-1028\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49-300x300.png 300w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49-150x150.png 150w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49-768x768.png 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49-1024x1024.png 1024w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/11\/W49.png 1025w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Despu\u00e9s de la cena en el hotel rural, decidimos caminar por la granja antes de volver a nuestra habitaci\u00f3n. Seguimos el camino de grava, brazo con brazo, por los oscuros alrededores, mirando las estrellas y bebiendo la noche silenciosa.<\/p>\n\n\n\n<p>Cuando nos acerc\u00e1bamos a la caballeriza, dos perros corrieron hacia nosotros, ladrando a pleno pulm\u00f3n. Pude sentir nuestros cuerpos endurecerse, nuestros corazones latir m\u00e1s r\u00e1pido y dudamos si continuar el paseo por este camino.<\/p>\n\n\n\n<p>\u2014Shhhh \u2014susurr\u00e9 en la direcci\u00f3n por donde se acercaban los perros y extend\u00ed mi brazo con la palma de la mano abierta.<\/p>\n\n\n\n<p>Los perros se detuvieron y tomaron una posici\u00f3n defensiva en medio del patio frente a la caballeriza, gru\u00f1endo en nuestra direcci\u00f3n. Aunque todav\u00eda tensos, pude sentir nuestros cuerpos relajarse un poco al calmarse la situaci\u00f3n.<\/p>\n\n\n\n<p>\u2014Guau, eso fue incre\u00edble \u2014dijiste en voz baja cuando hab\u00edamos pasado la caballeriza y tomado otro camino de vuelta hacia el hotel\u2014. \u00a1C\u00f3mo lograste calmar a esos perros!<\/p>\n\n\n\n<p>\u2014Eh&#8230; \u2014admit\u00ed\u2014, la verdad es que no era a los perros a quienes intentaba calmar.<\/p>\n\n\n\n<p>\u2014Oh \u2014dijiste, apoyando tu cabeza en mi pecho\u2014. Entonces intentabas calmarme a m\u00ed. Pues eso funcion\u00f3 tambi\u00e9n.<\/p>\n\n\n\n<p>\u00abEn realidad, tampoco trataba de calmarte a ti\u00bb, pens\u00e9, pero decid\u00ed guardarme el hecho de que mi acci\u00f3n hab\u00eda sido puramente introvertida.<\/p>\n\n\n\n<aside class=\"wp-block-group book-ad has-text-color has-background\" style=\"color:#000000;background-color:#dcd0ff\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-small-font-size\" style=\"line-height:.9\">LIBRO<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg\" alt=\"52 Momentos \u2014 Dise\u00f1o de tapa: Ana Pi\u00f1eyro\" class=\"wp-image-1274 size-full\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg 778w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-228x300.jpg 228w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-768x1011.jpg 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-900x1184.jpg 900w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-500x658.jpg 500w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos.jpg 1025w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">52 momentos<\/h4>\n\n\n\n<p>Este microrrelato apareci\u00f3 en la colecci\u00f3n de microrrelatos 52 momentos.<\/p>\n\n\n\n<p><em>52 momentos<\/em> est\u00e1 disponible en edici\u00f3n de bolsillo en <a href=\"https:\/\/www.amazon.es\/52-momentos-B%C3%B6rkur-Sigurbj%C3%B6rnsson\/dp\/9935933776\/\" target=\"_blank\" rel=\"noopener\">Amazon<\/a> y <a href=\"https:\/\/www.barnesandnoble.com\/w\/52-momentos-b-rkur-sigurbj-rnsson\/1129432380\" target=\"_blank\" rel=\"noopener\">Barnes and Noble<\/a> y como libro electr\u00f3nico en <a href=\"https:\/\/www.amazon.es\/52-momentos-Spanish-B%C3%B6rkur-Sigurbj%C3%B6rnsson-ebook\/dp\/B079RKXQN6\/\" target=\"_blank\" rel=\"noopener\">Amazon Kindle Store<\/a>, <a href=\"https:\/\/books.apple.com\/us\/book\/52-momentos\/id1347928626\" target=\"_blank\" rel=\"noopener\">Apple Books<\/a>, <a href=\"https:\/\/www.kobo.com\/us\/en\/ebook\/52-momentos\" target=\"_blank\" rel=\"noopener\">Kobo<\/a>, y <a href=\"https:\/\/www.storytel.com\/es\/es\/books\/52-momentos-2028514\" target=\"_blank\" rel=\"noopener\">Storytel<\/a>.<\/p>\n\n\n\n<p>A\u00f1ade el libro a tu lista de lectura de <a href=\"https:\/\/www.goodreads.com\/book\/show\/38506950-52-momentos\" target=\"_blank\" rel=\"noopener\">Goodreads<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/urbanvolcano.net\/es\/52-momentos\/\" style=\"border-radius:50px;color:#ffffff;background-color:#000000\">m\u00e1s sobre el libro<\/a><\/div>\n<\/div>\n<\/div><\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Microrrelato de B\u00f6rkur Sigurbj\u00f6rnsson. Un hombre necesita aplicar sus poderes sobrenaturales cuando dos perros se acercan.<\/p>\n","protected":false},"author":1,"featured_media":1028,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[29,27],"class_list":["post-1027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-microrrelatos","tag-animales","tag-viajes","col-md-6 col-sm-6"],"_links":{"self":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/1027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/comments?post=1027"}],"version-history":[{"count":8,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/1027\/revisions"}],"predecessor-version":[{"id":1783,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/1027\/revisions\/1783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media\/1028"}],"wp:attachment":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media?parent=1027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/categories?post=1027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/tags?post=1027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}