{"id":770,"date":"2017-02-19T07:00:04","date_gmt":"2017-02-19T07:00:04","guid":{"rendered":"http:\/\/urbanvolcano.net\/es\/?p=770"},"modified":"2025-03-30T20:32:10","modified_gmt":"2025-03-30T20:32:10","slug":"libertad","status":"publish","type":"post","link":"https:\/\/urbanvolcano.net\/es\/libertad\/","title":{"rendered":"Libertad"},"content":{"rendered":"\n<aside class=\"other-formats\">Otros formatos: <a title=\"Libertad (PDF)\" href=\"https:\/\/urbanvolcano.net\/ebooks\/es\/pdf\/libertad.pdf\">PDF<\/a> | <a title=\"Freedom (english)\" href=\"https:\/\/urbanvolcano.net\/en\/freedom\/\">english<\/a> | <a title=\"Frelsi (\u00edslenska)\" href=\"https:\/\/urbanvolcano.net\/is\/frelsi\/\">\u00edslenska<\/a><\/aside>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1.png\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1-300x300.png\" alt=\"Libertad \u2014 Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson\" class=\"wp-image-1084\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1-300x300.png 300w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1-150x150.png 150w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1-768x768.png 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1-1024x1024.png 1024w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/02\/W07-1.png 1025w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Condujimos a trav\u00e9s de los humedales al sur de la Amazonia; un conductor, un gu\u00eda y cuatro turistas. Mir\u00e1bamos atentos en todas las direcciones en busca del gran premio.<\/p>\n\n\n\n<p>\u2014Shhh \u2014dijo el gu\u00eda de repente y se\u00f1al\u00f3 hacia el horizonte. Seguimos su indicaci\u00f3n r\u00edo abajo y hacia la orilla opuesta. El conductor disminuy\u00f3 la velocidad y condujo cuidadosamente a lo largo del r\u00edo.<\/p>\n\n\n\n<p>Cog\u00ed mi c\u00e1mara y apunt\u00e9 el lente. El <em>jeep<\/em> par\u00f3 y saqu\u00e9 una foto. Baj\u00e9 la c\u00e1mara y mir\u00e9 al gato a los ojos \u2014al jaguar\u2014 que estaba parado majestuosamente en la orilla del r\u00edo.<\/p>\n\n\n\n<p>Respir\u00e9 hondo y sent\u00ed una sensaci\u00f3n de libertad cruzando por mi cuerpo. Esto era exactamente lo que ten\u00eda en mente cuando un mes atr\u00e1s hab\u00eda decidido dejar mi trabajo, hacer un viaje y buscar aventuras.<\/p>\n\n\n\n<aside class=\"wp-block-group book-ad has-text-color has-background\" style=\"color:#000000;background-color:#dcd0ff\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-small-font-size\" style=\"line-height:.9\">LIBRO<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg\" alt=\"52 Momentos \u2014 Dise\u00f1o de tapa: Ana Pi\u00f1eyro\" class=\"wp-image-1274 size-full\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg 778w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-228x300.jpg 228w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-768x1011.jpg 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-900x1184.jpg 900w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-500x658.jpg 500w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos.jpg 1025w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">52 momentos<\/h4>\n\n\n\n<p>Este microrrelato apareci\u00f3 en la colecci\u00f3n de microrrelatos 52 momentos.<\/p>\n\n\n\n<p><em>52 momentos<\/em> est\u00e1 disponible en edici\u00f3n de bolsillo en <a href=\"https:\/\/www.amazon.es\/52-momentos-B%C3%B6rkur-Sigurbj%C3%B6rnsson\/dp\/9935933776\/\" target=\"_blank\" rel=\"noopener\">Amazon<\/a> y <a href=\"https:\/\/www.barnesandnoble.com\/w\/52-momentos-b-rkur-sigurbj-rnsson\/1129432380\" target=\"_blank\" rel=\"noopener\">Barnes and Noble<\/a> y como libro electr\u00f3nico en <a href=\"https:\/\/www.amazon.es\/52-momentos-Spanish-B%C3%B6rkur-Sigurbj%C3%B6rnsson-ebook\/dp\/B079RKXQN6\/\" target=\"_blank\" rel=\"noopener\">Amazon Kindle Store<\/a>, <a href=\"https:\/\/books.apple.com\/us\/book\/52-momentos\/id1347928626\" target=\"_blank\" rel=\"noopener\">Apple Books<\/a>, <a href=\"https:\/\/www.kobo.com\/us\/en\/ebook\/52-momentos\" target=\"_blank\" rel=\"noopener\">Kobo<\/a>, y <a href=\"https:\/\/www.storytel.com\/es\/es\/books\/52-momentos-2028514\" target=\"_blank\" rel=\"noopener\">Storytel<\/a>.<\/p>\n\n\n\n<p>A\u00f1ade el libro a tu lista de lectura de <a href=\"https:\/\/www.goodreads.com\/book\/show\/38506950-52-momentos\" target=\"_blank\" rel=\"noopener\">Goodreads<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/urbanvolcano.net\/es\/52-momentos\/\" style=\"border-radius:50px;color:#ffffff;background-color:#000000\">m\u00e1s sobre el libro<\/a><\/div>\n<\/div>\n<\/div><\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Microrrelato de B\u00f6rkur Sigurbj\u00f6rnsson. Una persona en busca de aventuras en los humedales de Brazil.<\/p>\n","protected":false},"author":1,"featured_media":1084,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[29,36,27],"class_list":["post-770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-microrrelatos","tag-animales","tag-naturaleza","tag-viajes","col-md-6 col-sm-6"],"_links":{"self":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":8,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"predecessor-version":[{"id":1740,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/770\/revisions\/1740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media\/1084"}],"wp:attachment":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}