{"id":913,"date":"2017-06-30T07:00:47","date_gmt":"2017-06-30T07:00:47","guid":{"rendered":"http:\/\/urbanvolcano.net\/es\/?p=913"},"modified":"2025-03-30T20:45:52","modified_gmt":"2025-03-30T20:45:52","slug":"silencio-agradable","status":"publish","type":"post","link":"https:\/\/urbanvolcano.net\/es\/silencio-agradable\/","title":{"rendered":"Silencio agradable"},"content":{"rendered":"\n<aside class=\"other-formats\">Otros formatos: <a title=\"Silencio agradable (PDF)\" href=\"https:\/\/urbanvolcano.net\/ebooks\/es\/pdf\/silencio-agradable.pdf\">PDF<\/a> | <a title=\"Comfortable silence (english)\" href=\"https:\/\/urbanvolcano.net\/en\/comfortable-silence\/\">english<\/a> | <a title=\"\u00de\u00e6gileg \u00fe\u00f6gn (\u00edslenska)\" href=\"https:\/\/urbanvolcano.net\/is\/thaegileg-thogn\/\">\u00edslenska<\/a><\/aside>\n\n\n<div class=\"wp-block-image is-resized\">\n<figure class=\"alignright size-medium\"><a href=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26.png\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26-300x300.png\" alt=\"Silencio agradable \u2014 Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson\" class=\"wp-image-1128\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26-300x300.png 300w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26-150x150.png 150w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26-768x768.png 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26-1024x1024.png 1024w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2017\/06\/W26.png 1025w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption class=\"wp-element-caption\">Ilustraci\u00f3n de B\u00f6rkur Sigurbj\u00f6rnsson<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Estamos los tres sentados juntos en el sal\u00f3n \u2014mis anfitriones y yo\u2014 cada uno en su mundo. Ella lee un peri\u00f3dico. \u00c9l juega un videojuego en su tableta. Yo escribo. En un primer plano, hay silencio; en el fondo, jazz en un volumen bajo. De vez en cuando ella nos cuenta noticias del peri\u00f3dico. Nosotros escuchamos, discutimos y volvemos a nuestro propio mundo.<\/p>\n\n\n\n<aside class=\"wp-block-group book-ad has-text-color has-background\" style=\"color:#000000;background-color:#dcd0ff\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center has-small-font-size\" style=\"line-height:.9\">LIBRO<\/p>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:33% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"778\" height=\"1024\" src=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg\" alt=\"52 Momentos \u2014 Dise\u00f1o de tapa: Ana Pi\u00f1eyro\" class=\"wp-image-1274 size-full\" srcset=\"https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-778x1024.jpg 778w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-228x300.jpg 228w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-768x1011.jpg 768w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-900x1184.jpg 900w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos-500x658.jpg 500w, https:\/\/urbanvolcano.net\/es\/wp-content\/uploads\/2018\/02\/52-Momentos.jpg 1025w\" sizes=\"auto, (max-width: 778px) 100vw, 778px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<h4 class=\"wp-block-heading\">52 momentos<\/h4>\n\n\n\n<p>Este microrrelato apareci\u00f3 en la colecci\u00f3n de microrrelatos 52 momentos.<\/p>\n\n\n\n<p><em>52 momentos<\/em> est\u00e1 disponible en edici\u00f3n de bolsillo en <a href=\"https:\/\/www.amazon.es\/52-momentos-B%C3%B6rkur-Sigurbj%C3%B6rnsson\/dp\/9935933776\/\" target=\"_blank\" rel=\"noopener\">Amazon<\/a> y <a href=\"https:\/\/www.barnesandnoble.com\/w\/52-momentos-b-rkur-sigurbj-rnsson\/1129432380\" target=\"_blank\" rel=\"noopener\">Barnes and Noble<\/a> y como libro electr\u00f3nico en <a href=\"https:\/\/www.amazon.es\/52-momentos-Spanish-B%C3%B6rkur-Sigurbj%C3%B6rnsson-ebook\/dp\/B079RKXQN6\/\" target=\"_blank\" rel=\"noopener\">Amazon Kindle Store<\/a>, <a href=\"https:\/\/books.apple.com\/us\/book\/52-momentos\/id1347928626\" target=\"_blank\" rel=\"noopener\">Apple Books<\/a>, <a href=\"https:\/\/www.kobo.com\/us\/en\/ebook\/52-momentos\" target=\"_blank\" rel=\"noopener\">Kobo<\/a>, y <a href=\"https:\/\/www.storytel.com\/es\/es\/books\/52-momentos-2028514\" target=\"_blank\" rel=\"noopener\">Storytel<\/a>.<\/p>\n\n\n\n<p>A\u00f1ade el libro a tu lista de lectura de <a href=\"https:\/\/www.goodreads.com\/book\/show\/38506950-52-momentos\" target=\"_blank\" rel=\"noopener\">Goodreads<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-499968f5 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-50\"><a class=\"wp-block-button__link has-text-color has-background wp-element-button\" href=\"https:\/\/urbanvolcano.net\/es\/52-momentos\/\" style=\"border-radius:50px;color:#ffffff;background-color:#000000\">m\u00e1s sobre el libro<\/a><\/div>\n<\/div>\n<\/div><\/aside>\n","protected":false},"excerpt":{"rendered":"<p>Microrrelato de B\u00f6rkur Sigurbj\u00f6rnsson. Un silencio agradable en el primer plano y jazz en un volumen bajo en el fondo.<\/p>\n","protected":false},"author":1,"featured_media":1128,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[33,35,11],"class_list":["post-913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-microrrelatos","tag-juegos","tag-literatura","tag-sobre-escribir","col-md-6 col-sm-6"],"_links":{"self":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/comments?post=913"}],"version-history":[{"count":9,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/913\/revisions"}],"predecessor-version":[{"id":1759,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/posts\/913\/revisions\/1759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media\/1128"}],"wp:attachment":[{"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/media?parent=913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/categories?post=913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbanvolcano.net\/es\/wp-json\/wp\/v2\/tags?post=913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}